{"id":217,"date":"2016-05-04T16:40:30","date_gmt":"2016-05-04T14:40:30","guid":{"rendered":"http:\/\/bsfv.de\/wordpress\/?p=217"},"modified":"2016-05-09T08:59:18","modified_gmt":"2016-05-09T06:59:18","slug":"bsfv-suedwestpokalfischen-der-jugend-am-08-10-2011","status":"publish","type":"post","link":"http:\/\/bsfv.de\/wordpress\/jugend\/bsfv-suedwestpokalfischen-der-jugend-am-08-10-2011\/","title":{"rendered":"BSFV S\u00fcdwestpokalfischen der Jugend am 08.10.2011"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-thumbnail wp-image-551\" src=\"http:\/\/bsfv.de\/wordpress\/wp-content\/uploads\/2016\/05\/sw-pokal_jugend2011_1Klein-150x150.jpg\" alt=\"sw-pokal_jugend2011_1Klein\" width=\"150\" height=\"150\" \/><\/p>\n<div class=\"entry\">\n<p style=\"text-align: justify;\">Bei Regen und Sturm traf sich die BSFV-Jugend mit ihren Betreuern am Samstag, den 08.10.2011, an der Autobahnrastst\u00e4tte Wunnenstein und fuhr gemeinsam zum Vereinsheim des Kreisfischervereins T\u00fcbingen. Wir waren schon zeitig dort und so konnten wir noch in Ruhe zusammen mit den Jugendlichen fr\u00fchst\u00fccken.<\/p>\n<p style=\"text-align: justify;\">Als alle Teilnehmer angekommen waren, fuhren wir nach dem Losen zu den Angelpl\u00e4tzen. Der Neckar ist ein ruhiges Fliessgew\u00e4sser mit 1,20 m Tiefe und es konnte mit Stippangel und Feederrute gefischt werden. Die Pl\u00e4tze waren gut zu beangeln &#8211; also jugendgerecht &#8211; nur die Fische wollten nicht so richtig beissen und so gab es keine gro\u00dfen F\u00e4nge. Aber wenn nichts geht, muss man auch mit wenig Fisch zufrieden sein &#8211; daf\u00fcr hielt wenigstens das Wetter \u00fcber das ganze Fischen.<\/p>\n<p style=\"text-align: justify;\">Nach dem Fischen wurde am Platz gewogen. Die Platzierungen unserer Jugendlichen war gut, aber f\u00fcr die vorderen Pl\u00e4tze in der Mannschaftswertung reichte es nicht ganz. Roberto Vilardo vom ASV Sandhofen wurde mit 310gr. Sektorensieger, dem h\u00f6chsten Fanggewicht an diesem Tag. In anderen Sektoren belegten Philipp Appel vom ASV Sandhofen und Fabian Wolf vom ASV St. Leon zweite Pl\u00e4tze. Unsere anderen Jugendlichen gingen leider leer aus.<\/p>\n<p><strong>Folgende Platzierungen wurden erreicht:<\/strong><\/p>\n<ul>\n<li>1. Platz: Landesverband Saarland I<\/li>\n<li>2. Platz: Landesverband Saarland II<\/li>\n<li>3. Platz: BSFV II<\/li>\n<li>4. Platz: Rheinland-Pfalz<\/li>\n<li>5. Platz: BSFV I<\/li>\n<li>6. Platz: VFG Baden-W\u00fcrttemberg<\/li>\n<\/ul>\n<p>Nach der Preisverteilung traten wir den Heimweg an und kamen wohlbehalten zu Hause an. Vielen Dank an die Betreuer, die wieder einen guten Job gemacht haben und einen Dank an den Kreisfischerverein T\u00fcbingen f\u00fcr die Ausrichtung der Veranstaltung.<\/p>\n<p>Petri Heil,<\/p>\n<p>Berti Schmitt, BSFV Jugendleiter<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bei Regen und Sturm traf sich die BSFV-Jugend mit ihren Betreuern am Samstag, den 08.10.2011, an der Autobahnrastst\u00e4tte Wunnenstein und fuhr gemeinsam zum Vereinsheim des Kreisfischervereins T\u00fcbingen. Wir waren schon zeitig dort und so konnten wir noch in Ruhe zusammen mit den Jugendlichen fr\u00fchst\u00fccken. Als alle Teilnehmer angekommen waren, fuhren wir nach dem Losen zu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/bsfv.de\/wordpress\/wp-json\/wp\/v2\/posts\/217"}],"collection":[{"href":"http:\/\/bsfv.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/bsfv.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/bsfv.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/bsfv.de\/wordpress\/wp-json\/wp\/v2\/comments?post=217"}],"version-history":[{"count":2,"href":"http:\/\/bsfv.de\/wordpress\/wp-json\/wp\/v2\/posts\/217\/revisions"}],"predecessor-version":[{"id":595,"href":"http:\/\/bsfv.de\/wordpress\/wp-json\/wp\/v2\/posts\/217\/revisions\/595"}],"wp:attachment":[{"href":"http:\/\/bsfv.de\/wordpress\/wp-json\/wp\/v2\/media?parent=217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bsfv.de\/wordpress\/wp-json\/wp\/v2\/categories?post=217"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bsfv.de\/wordpress\/wp-json\/wp\/v2\/tags?post=217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}